{"id":20985,"date":"2016-10-31T20:18:34","date_gmt":"2016-10-31T20:18:34","guid":{"rendered":"https:\/\/www.societateamuzicala.ro\/societateateologica\/?p=20985"},"modified":"2016-10-31T20:19:29","modified_gmt":"2016-10-31T20:19:29","slug":"atelierele-patriarhiei","status":"publish","type":"post","link":"https:\/\/www.societateamuzicala.ro\/societateateologica\/atelierele-patriarhiei","title":{"rendered":"Atelierele Patriarhiei"},"content":{"rendered":"<p><strong>Atelierele Patriarhiei<\/strong> reprezinta locul unde se confectioneaza toate obiectele de cult care se utilizeaza in cadrul cultului ortodox al <a href=\"https:\/\/www.societateamuzicala.ro\/societateateologica\/biserica-ortodoxa-romana\" target=\"_blank\">Bisericii Ortodoxe Romane.<\/a><\/p>\n<p>Astfel, prin centrele de la Popesti-Leordeni, Manastirea Tiganesti si Manastirea Pasarea, <strong>Atelierele Patriarhiei Romane<\/strong> pun la dispozitia celor interesati o gama completa de materiale si obiecte de uz bisericesc precum: mobilier lemn sculptat, vesminte bisericesti, obiecte bisericesti de cult, policandre, icoane pictate pe lemn, icoane ferecate in metal, racle pentru Sfinte Moaste, cruci pectorale, de binecuvantare, set de sfinte vase, cristelnite, engolpioane si multe alte obiecte.<\/p>\n<p>Organizarea <strong>Atelierelor Patriarhiei<\/strong> se\u00a0 datoreaza vrednicului de pomenire PF Parinte Patriarh Justinian, cel care a sprijinit aparitia si dezvoltarea acestora.<\/p>\n<p><strong>Atelierele Patriarhiei Romane<\/strong> isi desfasoara activitatea prin cele 3 centre de productie aflate: Manastirea Sfintilor Romani (Popesti-Leordeni), Manastirea Pasarea si manastirea Tiganesti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atelierele Patriarhiei reprezinta locul unde se confectioneaza toate obiectele de cult care se utilizeaza in cadrul cultului ortodox al Bisericii Ortodoxe Romane. Astfel, prin centrele de la Popesti-Leordeni, Manastirea Tiganesti si Manastirea Pasarea, Atelierele Patriarhiei Romane pun la dispozitia celor interesati o gama completa de materiale si obiecte de uz bisericesc precum: mobilier lemn sculptat, [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2909],"tags":[5411,5425,5422,5419,5420,5423,5417,5416,5412,5424,5426,5414,5427,5428,5415,5418,5421,5413],"class_list":["post-20985","post","type-post","status-publish","format-standard","hentry","category-librarii-si-magazine-de-cult","tag-atelierele-patriarhiei","tag-atelierele-patriarhiei-romane","tag-cristelnite","tag-cruci-pectorale","tag-de-binecuvantare","tag-engolpioane","tag-icoane-ferecate-in-metal","tag-icoane-pictate-pe-lemn","tag-mobilier-lemn-sculptat","tag-obiecte-bisericesti","tag-obiecte-bisericesti-bor","tag-obiecte-bisericesti-de-cult","tag-obiecte-bisericesti-patriarhia","tag-obiecte-bisericesti-patriarhia-romana","tag-policandre","tag-racle-pentru-sfinte-moaste","tag-set-de-sfinte-vase","tag-vesminte-bisericesti"],"acf":{"cc_filter":["ortodox"],"poza_fixa":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-content\/uploads\/2016\/10\/1.Atelierele-Patriarhiei.jpg","url_poza_fixa":"","oras":"Bucuresti","in_strainatate":false,"pian":false,"orga":false,"data1":"","data2":"","afiseaza_data_post":false,"acf_sala":"","centru_cultural":"","articole_parinte":"","articole_relationate":"","coordonate":false,"tab1_nume":"Despre","tab3":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atelierele Patriarhiei - Societatea Teologica<\/title>\n<meta name=\"description\" content=\"Atelierele Patriarhiei reprezinta locul unde se confectioneaza toate obiectele de cult care se utilizeaza in cadrul cultului ortodox\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.societateamuzicala.ro\/societateateologica\/atelierele-patriarhiei\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atelierele Patriarhiei - Societatea Teologica\" \/>\n<meta property=\"og:description\" content=\"Atelierele Patriarhiei reprezinta locul unde se confectioneaza toate obiectele de cult care se utilizeaza in cadrul cultului ortodox\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.societateamuzicala.ro\/societateateologica\/atelierele-patriarhiei\" \/>\n<meta property=\"og:site_name\" content=\"Societatea Teologica\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-31T20:18:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-31T20:19:29+00:00\" \/>\n<meta name=\"author\" content=\"Daniel Catoi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scris de\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Catoi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Timp estimat pentru citire\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/atelierele-patriarhiei#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/atelierele-patriarhiei\"},\"author\":{\"name\":\"Daniel Catoi\",\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/#\\\/schema\\\/person\\\/594fa82aad1702ebd9e24df9c9f2f709\"},\"headline\":\"Atelierele Patriarhiei\",\"datePublished\":\"2016-10-31T20:18:34+00:00\",\"dateModified\":\"2016-10-31T20:19:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/atelierele-patriarhiei\"},\"wordCount\":131,\"commentCount\":0,\"keywords\":[\"Atelierele Patriarhiei\",\"atelierele patriarhiei romane\",\"cristelnite\",\"cruci pectorale\",\"de binecuvantare\",\"engolpioane\",\"icoane ferecate in metal\",\"icoane pictate pe lemn\",\"mobilier lemn sculptat\",\"obiecte bisericesti\",\"obiecte bisericesti bor\",\"obiecte bisericesti de cult\",\"obiecte bisericesti patriarhia\",\"obiecte bisericesti patriarhia romana\",\"policandre\",\"racle pentru Sfinte Moaste\",\"set de sfinte vase\",\"vesminte bisericesti\"],\"articleSection\":[\"Librarii si magazine de cult\"],\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/atelierele-patriarhiei#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/atelierele-patriarhiei\",\"url\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/atelierele-patriarhiei\",\"name\":\"Atelierele Patriarhiei - Societatea Teologica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/#website\"},\"datePublished\":\"2016-10-31T20:18:34+00:00\",\"dateModified\":\"2016-10-31T20:19:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/#\\\/schema\\\/person\\\/594fa82aad1702ebd9e24df9c9f2f709\"},\"description\":\"Atelierele Patriarhiei reprezinta locul unde se confectioneaza toate obiectele de cult care se utilizeaza in cadrul cultului ortodox\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/atelierele-patriarhiei#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/atelierele-patriarhiei\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/atelierele-patriarhiei#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Acas\u0103\",\"item\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atelierele Patriarhiei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/#website\",\"url\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/\",\"name\":\"Societatea Teologica\",\"description\":\"Teologia si institutiile ei din Romania; Societatea Teologica este o platforma de informatie, de marketing si project management teologic, facuta spre a asigura o legatura directa si permanenta intre teologie si oamenii ei din toate cultele active la noi in tara, pe de o parte, si lumea businessului si reprezentantii ei, de cealalta parte.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/#\\\/schema\\\/person\\\/594fa82aad1702ebd9e24df9c9f2f709\",\"name\":\"Daniel Catoi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0882a218c936889972a11c796e8ed91e0aff99b92af7212c04f740da3928233?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0882a218c936889972a11c796e8ed91e0aff99b92af7212c04f740da3928233?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0882a218c936889972a11c796e8ed91e0aff99b92af7212c04f740da3928233?s=96&d=mm&r=g\",\"caption\":\"Daniel Catoi\"},\"url\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/author\\\/daniel-catoi\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atelierele Patriarhiei - Societatea Teologica","description":"Atelierele Patriarhiei reprezinta locul unde se confectioneaza toate obiectele de cult care se utilizeaza in cadrul cultului ortodox","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.societateamuzicala.ro\/societateateologica\/atelierele-patriarhiei","og_locale":"ro_RO","og_type":"article","og_title":"Atelierele Patriarhiei - Societatea Teologica","og_description":"Atelierele Patriarhiei reprezinta locul unde se confectioneaza toate obiectele de cult care se utilizeaza in cadrul cultului ortodox","og_url":"https:\/\/www.societateamuzicala.ro\/societateateologica\/atelierele-patriarhiei","og_site_name":"Societatea Teologica","article_published_time":"2016-10-31T20:18:34+00:00","article_modified_time":"2016-10-31T20:19:29+00:00","author":"Daniel Catoi","twitter_card":"summary_large_image","twitter_misc":{"Scris de":"Daniel Catoi","Timp estimat pentru citire":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/atelierele-patriarhiei#article","isPartOf":{"@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/atelierele-patriarhiei"},"author":{"name":"Daniel Catoi","@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/#\/schema\/person\/594fa82aad1702ebd9e24df9c9f2f709"},"headline":"Atelierele Patriarhiei","datePublished":"2016-10-31T20:18:34+00:00","dateModified":"2016-10-31T20:19:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/atelierele-patriarhiei"},"wordCount":131,"commentCount":0,"keywords":["Atelierele Patriarhiei","atelierele patriarhiei romane","cristelnite","cruci pectorale","de binecuvantare","engolpioane","icoane ferecate in metal","icoane pictate pe lemn","mobilier lemn sculptat","obiecte bisericesti","obiecte bisericesti bor","obiecte bisericesti de cult","obiecte bisericesti patriarhia","obiecte bisericesti patriarhia romana","policandre","racle pentru Sfinte Moaste","set de sfinte vase","vesminte bisericesti"],"articleSection":["Librarii si magazine de cult"],"inLanguage":"ro-RO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.societateamuzicala.ro\/societateateologica\/atelierele-patriarhiei#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/atelierele-patriarhiei","url":"https:\/\/www.societateamuzicala.ro\/societateateologica\/atelierele-patriarhiei","name":"Atelierele Patriarhiei - Societatea Teologica","isPartOf":{"@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/#website"},"datePublished":"2016-10-31T20:18:34+00:00","dateModified":"2016-10-31T20:19:29+00:00","author":{"@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/#\/schema\/person\/594fa82aad1702ebd9e24df9c9f2f709"},"description":"Atelierele Patriarhiei reprezinta locul unde se confectioneaza toate obiectele de cult care se utilizeaza in cadrul cultului ortodox","breadcrumb":{"@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/atelierele-patriarhiei#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.societateamuzicala.ro\/societateateologica\/atelierele-patriarhiei"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/atelierele-patriarhiei#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Acas\u0103","item":"https:\/\/www.societateamuzicala.ro\/societateateologica"},{"@type":"ListItem","position":2,"name":"Atelierele Patriarhiei"}]},{"@type":"WebSite","@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/#website","url":"https:\/\/www.societateamuzicala.ro\/societateateologica\/","name":"Societatea Teologica","description":"Teologia si institutiile ei din Romania; Societatea Teologica este o platforma de informatie, de marketing si project management teologic, facuta spre a asigura o legatura directa si permanenta intre teologie si oamenii ei din toate cultele active la noi in tara, pe de o parte, si lumea businessului si reprezentantii ei, de cealalta parte.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.societateamuzicala.ro\/societateateologica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Person","@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/#\/schema\/person\/594fa82aad1702ebd9e24df9c9f2f709","name":"Daniel Catoi","image":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/secure.gravatar.com\/avatar\/c0882a218c936889972a11c796e8ed91e0aff99b92af7212c04f740da3928233?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c0882a218c936889972a11c796e8ed91e0aff99b92af7212c04f740da3928233?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c0882a218c936889972a11c796e8ed91e0aff99b92af7212c04f740da3928233?s=96&d=mm&r=g","caption":"Daniel Catoi"},"url":"https:\/\/www.societateamuzicala.ro\/societateateologica\/author\/daniel-catoi"}]}},"_links":{"self":[{"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/posts\/20985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/comments?post=20985"}],"version-history":[{"count":0,"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/posts\/20985\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/media?parent=20985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/categories?post=20985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/tags?post=20985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}