{"id":19597,"date":"2016-07-17T17:20:47","date_gmt":"2016-07-17T17:20:47","guid":{"rendered":"https:\/\/www.societateamuzicala.ro\/societateateologica\/?p=19597"},"modified":"2016-07-19T18:39:15","modified_gmt":"2016-07-19T18:39:15","slug":"trinitas-tv","status":"publish","type":"post","link":"https:\/\/www.societateamuzicala.ro\/societateateologica\/trinitas-tv","title":{"rendered":"Trinitas TV"},"content":{"rendered":"<p>Trinitas TV este postul de televiziune oficial al Patriarhiei Romane, care emite din anul 2007, 24 de ore din 24. Prin intermediul acestui post tv cu caracter religios-cultural, Patriarhia Romana informeaza si societatea contemporana in ceea ce priveste activitatea religios-teologica a Bisericii Ortodoxe Romane.<\/p>\n<p>Prin intermediul emisiunilor propuse, Trinitas TV tine legatura cu opinia publica si transmite in spatiul public informatii privind lucrarea pastoral-misionara, sociala, teologic-educationala sau culturala a Bisericii Ortodoxe, venind in intampinarea publicului, prin intermediul \u00a0noilor mijloace de comunicare, specifice societatii contemporane.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trinitas TV este postul de televiziune oficial al Patriarhiei Romane, care emite din anul 2007, 24 de ore din 24. Prin intermediul acestui post tv cu caracter religios-cultural, Patriarhia Romana informeaza si societatea contemporana in ceea ce priveste activitatea religios-teologica a Bisericii Ortodoxe Romane. Prin intermediul emisiunilor propuse, Trinitas TV tine legatura cu opinia publica [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2801],"tags":[3363,3361,3362],"class_list":["post-19597","post","type-post","status-publish","format-standard","hentry","category-media-si-publicatii","tag-televiziunea-patriarhiei-romane","tag-trinitas-tv","tag-tv-trinitas"],"acf":{"cc_filter":["ortodox"],"poza_fixa":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-content\/uploads\/2016\/07\/TV-Trinitas.jpg","url_poza_fixa":"","oras":"Bucuresti","in_strainatate":false,"pian":false,"orga":false,"data1":"","data2":"","afiseaza_data_post":false,"articole_parinte":"","articole_relationate":"","coordonate":{"address":"Aleea Dealul Mitropoliei, nr. 25, sector 4","lat":"44.4255214","lng":"26.10012329999995"},"tab1_nume":"Despre","tab3":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trinitas TV - Societatea Teologica<\/title>\n<meta name=\"description\" content=\"Trinitas TV este postul de televiziune oficial al Patriarhiei Romane, care emite din anul 2007, 24 de ore din 24.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.societateamuzicala.ro\/societateateologica\/trinitas-tv\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trinitas TV - Societatea Teologica\" \/>\n<meta property=\"og:description\" content=\"Trinitas TV este postul de televiziune oficial al Patriarhiei Romane, care emite din anul 2007, 24 de ore din 24.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.societateamuzicala.ro\/societateateologica\/trinitas-tv\" \/>\n<meta property=\"og:site_name\" content=\"Societatea Teologica\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-17T17:20:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-19T18:39:15+00:00\" \/>\n<meta name=\"author\" content=\"Daniel Catoi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scris de\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Catoi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/trinitas-tv#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/trinitas-tv\"},\"author\":{\"name\":\"Daniel Catoi\",\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/#\\\/schema\\\/person\\\/594fa82aad1702ebd9e24df9c9f2f709\"},\"headline\":\"Trinitas TV\",\"datePublished\":\"2016-07-17T17:20:47+00:00\",\"dateModified\":\"2016-07-19T18:39:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/trinitas-tv\"},\"wordCount\":83,\"commentCount\":0,\"keywords\":[\"televiziunea patriarhiei romane\",\"Trinitas TV\",\"TV trinitas\"],\"articleSection\":[\"Media si publicatii\"],\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/trinitas-tv#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/trinitas-tv\",\"url\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/trinitas-tv\",\"name\":\"Trinitas TV - Societatea Teologica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/#website\"},\"datePublished\":\"2016-07-17T17:20:47+00:00\",\"dateModified\":\"2016-07-19T18:39:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/#\\\/schema\\\/person\\\/594fa82aad1702ebd9e24df9c9f2f709\"},\"description\":\"Trinitas TV este postul de televiziune oficial al Patriarhiei Romane, care emite din anul 2007, 24 de ore din 24.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/trinitas-tv#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/trinitas-tv\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/trinitas-tv#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Acas\u0103\",\"item\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trinitas TV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/#website\",\"url\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/\",\"name\":\"Societatea Teologica\",\"description\":\"Teologia si institutiile ei din Romania; Societatea Teologica este o platforma de informatie, de marketing si project management teologic, facuta spre a asigura o legatura directa si permanenta intre teologie si oamenii ei din toate cultele active la noi in tara, pe de o parte, si lumea businessului si reprezentantii ei, de cealalta parte.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/#\\\/schema\\\/person\\\/594fa82aad1702ebd9e24df9c9f2f709\",\"name\":\"Daniel Catoi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0882a218c936889972a11c796e8ed91e0aff99b92af7212c04f740da3928233?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0882a218c936889972a11c796e8ed91e0aff99b92af7212c04f740da3928233?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0882a218c936889972a11c796e8ed91e0aff99b92af7212c04f740da3928233?s=96&d=mm&r=g\",\"caption\":\"Daniel Catoi\"},\"url\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/author\\\/daniel-catoi\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trinitas TV - Societatea Teologica","description":"Trinitas TV este postul de televiziune oficial al Patriarhiei Romane, care emite din anul 2007, 24 de ore din 24.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.societateamuzicala.ro\/societateateologica\/trinitas-tv","og_locale":"ro_RO","og_type":"article","og_title":"Trinitas TV - Societatea Teologica","og_description":"Trinitas TV este postul de televiziune oficial al Patriarhiei Romane, care emite din anul 2007, 24 de ore din 24.","og_url":"https:\/\/www.societateamuzicala.ro\/societateateologica\/trinitas-tv","og_site_name":"Societatea Teologica","article_published_time":"2016-07-17T17:20:47+00:00","article_modified_time":"2016-07-19T18:39:15+00:00","author":"Daniel Catoi","twitter_card":"summary_large_image","twitter_misc":{"Scris de":"Daniel Catoi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/trinitas-tv#article","isPartOf":{"@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/trinitas-tv"},"author":{"name":"Daniel Catoi","@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/#\/schema\/person\/594fa82aad1702ebd9e24df9c9f2f709"},"headline":"Trinitas TV","datePublished":"2016-07-17T17:20:47+00:00","dateModified":"2016-07-19T18:39:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/trinitas-tv"},"wordCount":83,"commentCount":0,"keywords":["televiziunea patriarhiei romane","Trinitas TV","TV trinitas"],"articleSection":["Media si publicatii"],"inLanguage":"ro-RO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.societateamuzicala.ro\/societateateologica\/trinitas-tv#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/trinitas-tv","url":"https:\/\/www.societateamuzicala.ro\/societateateologica\/trinitas-tv","name":"Trinitas TV - Societatea Teologica","isPartOf":{"@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/#website"},"datePublished":"2016-07-17T17:20:47+00:00","dateModified":"2016-07-19T18:39:15+00:00","author":{"@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/#\/schema\/person\/594fa82aad1702ebd9e24df9c9f2f709"},"description":"Trinitas TV este postul de televiziune oficial al Patriarhiei Romane, care emite din anul 2007, 24 de ore din 24.","breadcrumb":{"@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/trinitas-tv#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.societateamuzicala.ro\/societateateologica\/trinitas-tv"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/trinitas-tv#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Acas\u0103","item":"https:\/\/www.societateamuzicala.ro\/societateateologica"},{"@type":"ListItem","position":2,"name":"Trinitas TV"}]},{"@type":"WebSite","@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/#website","url":"https:\/\/www.societateamuzicala.ro\/societateateologica\/","name":"Societatea Teologica","description":"Teologia si institutiile ei din Romania; Societatea Teologica este o platforma de informatie, de marketing si project management teologic, facuta spre a asigura o legatura directa si permanenta intre teologie si oamenii ei din toate cultele active la noi in tara, pe de o parte, si lumea businessului si reprezentantii ei, de cealalta parte.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.societateamuzicala.ro\/societateateologica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Person","@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/#\/schema\/person\/594fa82aad1702ebd9e24df9c9f2f709","name":"Daniel Catoi","image":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/secure.gravatar.com\/avatar\/c0882a218c936889972a11c796e8ed91e0aff99b92af7212c04f740da3928233?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c0882a218c936889972a11c796e8ed91e0aff99b92af7212c04f740da3928233?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c0882a218c936889972a11c796e8ed91e0aff99b92af7212c04f740da3928233?s=96&d=mm&r=g","caption":"Daniel Catoi"},"url":"https:\/\/www.societateamuzicala.ro\/societateateologica\/author\/daniel-catoi"}]}},"_links":{"self":[{"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/posts\/19597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/comments?post=19597"}],"version-history":[{"count":0,"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/posts\/19597\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/media?parent=19597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/categories?post=19597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/tags?post=19597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}