{"id":2756,"count":0,"description":"Principalele informatii, evenimente, stiri si aparitii editoriale din spatiul religios romanesc, care insumeaza atat cultele si asociatiile religioase recunoscute oficial de Statul Roman, cat si celelalte organizatii religioase existente in tara noastra.","link":"https:\/\/www.societateamuzicala.ro\/societateateologica\/category\/actualitatea-teologica","name":"Actualitatea teologica","slug":"actualitatea-teologica","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Actualitatea teologica - Societatea Teologica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.societateamuzicala.ro\/societateateologica\/category\/actualitatea-teologica\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Actualitatea teologica - Societatea Teologica\" \/>\n<meta property=\"og:description\" content=\"Principalele informatii, evenimente, stiri si aparitii editoriale din spatiul religios romanesc, care insumeaza atat cultele si asociatiile religioase recunoscute oficial de Statul Roman, cat si celelalte organizatii religioase existente in tara noastra.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.societateamuzicala.ro\/societateateologica\/category\/actualitatea-teologica\" \/>\n<meta property=\"og:site_name\" content=\"Societatea Teologica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/category\\\/actualitatea-teologica\",\"url\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/category\\\/actualitatea-teologica\",\"name\":\"Actualitatea teologica - Societatea Teologica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/category\\\/actualitatea-teologica#breadcrumb\"},\"inLanguage\":\"ro-RO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/category\\\/actualitatea-teologica#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Acas\u0103\",\"item\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualitatea teologica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/#website\",\"url\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/\",\"name\":\"Societatea Teologica\",\"description\":\"Teologia si institutiile ei din Romania; Societatea Teologica este o platforma de informatie, de marketing si project management teologic, facuta spre a asigura o legatura directa si permanenta intre teologie si oamenii ei din toate cultele active la noi in tara, pe de o parte, si lumea businessului si reprezentantii ei, de cealalta parte.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.societateamuzicala.ro\\\/societateateologica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Actualitatea teologica - Societatea Teologica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.societateamuzicala.ro\/societateateologica\/category\/actualitatea-teologica","og_locale":"ro_RO","og_type":"article","og_title":"Actualitatea teologica - Societatea Teologica","og_description":"Principalele informatii, evenimente, stiri si aparitii editoriale din spatiul religios romanesc, care insumeaza atat cultele si asociatiile religioase recunoscute oficial de Statul Roman, cat si celelalte organizatii religioase existente in tara noastra.","og_url":"https:\/\/www.societateamuzicala.ro\/societateateologica\/category\/actualitatea-teologica","og_site_name":"Societatea Teologica","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/category\/actualitatea-teologica","url":"https:\/\/www.societateamuzicala.ro\/societateateologica\/category\/actualitatea-teologica","name":"Actualitatea teologica - Societatea Teologica","isPartOf":{"@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/#website"},"breadcrumb":{"@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/category\/actualitatea-teologica#breadcrumb"},"inLanguage":"ro-RO"},{"@type":"BreadcrumbList","@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/category\/actualitatea-teologica#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Acas\u0103","item":"https:\/\/www.societateamuzicala.ro\/societateateologica"},{"@type":"ListItem","position":2,"name":"Actualitatea teologica"}]},{"@type":"WebSite","@id":"https:\/\/www.societateamuzicala.ro\/societateateologica\/#website","url":"https:\/\/www.societateamuzicala.ro\/societateateologica\/","name":"Societatea Teologica","description":"Teologia si institutiile ei din Romania; Societatea Teologica este o platforma de informatie, de marketing si project management teologic, facuta spre a asigura o legatura directa si permanenta intre teologie si oamenii ei din toate cultele active la noi in tara, pe de o parte, si lumea businessului si reprezentantii ei, de cealalta parte.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.societateamuzicala.ro\/societateateologica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/categories\/2756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.societateamuzicala.ro\/societateateologica\/wp-json\/wp\/v2\/posts?categories=2756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}